{"id":2789,"date":"2020-08-31T10:57:42","date_gmt":"2020-08-31T08:57:42","guid":{"rendered":"https:\/\/entreramasaventura.com\/?p=2789"},"modified":"2020-08-31T10:57:45","modified_gmt":"2020-08-31T08:57:45","slug":"horarios-de-septiembre","status":"publish","type":"post","link":"https:\/\/entreramasaventura.com\/en\/horarios-de-septiembre","title":{"rendered":"Horarios de Septiembre"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Primera semana abierto todos los d\u00edas de 11h a 17h.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Resto del mes, s\u00e1bados y domingos mismo horario.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Primera semana abierto todos los d\u00edas de 11h a 17h. Resto del mes, s\u00e1bados y domingos mismo horario.<\/p>\n","protected":false},"author":2,"featured_media":2790,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[27,32,7,40],"class_list":["post-2789","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar","tag-aventura","tag-conil","tag-tirolinas","tag-vacaciones-septiembre"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Entre Ramas Aventura\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/entreramasaventura.com\/en\/horarios-de-septiembre\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_GB\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Entre Ramas Aventura\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Horarios de Septiembre | Entre Ramas Aventura\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/entreramasaventura.com\/en\/horarios-de-septiembre\" \/>\n\t\t<meta property=\"fb:app_id\" content=\"2621646948123763\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/entreramasaventura.com\/wp-content\/uploads\/2020\/08\/A02AD2B8-B612-45E8-96CC-B97127C24C42-scaled.jpeg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/entreramasaventura.com\/wp-content\/uploads\/2020\/08\/A02AD2B8-B612-45E8-96CC-B97127C24C42-scaled.jpeg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1341\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-08-31T08:57:42+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-08-31T08:57:45+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/es-es.facebook.com\/entre.ramasaventuras\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Horarios de Septiembre | Entre Ramas Aventura\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/entreramasaventura.com\/wp-content\/uploads\/2020\/08\/A02AD2B8-B612-45E8-96CC-B97127C24C42-scaled.jpeg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/entreramasaventura.com\\\/en\\\/horarios-de-septiembre#article\",\"name\":\"Horarios de Septiembre | Entre Ramas Aventura\",\"headline\":\"Horarios de Septiembre\",\"author\":{\"@id\":\"https:\\\/\\\/entreramasaventura.com\\\/en\\\/author\\\/entreramas#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/entreramasaventura.com\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/entreramasaventura.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/A02AD2B8-B612-45E8-96CC-B97127C24C42-scaled.jpeg\",\"width\":2560,\"height\":1341},\"datePublished\":\"2020-08-31T10:57:42+02:00\",\"dateModified\":\"2020-08-31T10:57:45+02:00\",\"inLanguage\":\"en-GB\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/entreramasaventura.com\\\/en\\\/horarios-de-septiembre#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/entreramasaventura.com\\\/en\\\/horarios-de-septiembre#webpage\"},\"articleSection\":\"Sin categorizar, aventura, conil, tirolinas, vacaciones septiembre, Opcional\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/entreramasaventura.com\\\/en\\\/horarios-de-septiembre#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/entreramasaventura.com\\\/en#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/entreramasaventura.com\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/entreramasaventura.com\\\/category\\\/sin-categorizar#listItem\",\"name\":\"Sin categorizar\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/entreramasaventura.com\\\/category\\\/sin-categorizar#listItem\",\"position\":2,\"name\":\"Sin categorizar\",\"item\":\"https:\\\/\\\/entreramasaventura.com\\\/category\\\/sin-categorizar\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/entreramasaventura.com\\\/en\\\/horarios-de-septiembre#listItem\",\"name\":\"Horarios de Septiembre\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/entreramasaventura.com\\\/en#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/entreramasaventura.com\\\/en\\\/horarios-de-septiembre#listItem\",\"position\":3,\"name\":\"Horarios de Septiembre\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/entreramasaventura.com\\\/category\\\/sin-categorizar#listItem\",\"name\":\"Sin categorizar\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/entreramasaventura.com\\\/en\\\/#organization\",\"name\":\"Entre Ramas Aventura\",\"description\":\"Tu parque de aventura en los bosques ubicado en los pinares de Roche\",\"url\":\"https:\\\/\\\/entreramasaventura.com\\\/en\\\/\",\"telephone\":\"+34633698334\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/entreramasaventura.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/entre-ramas-logo.png\",\"@id\":\"https:\\\/\\\/entreramasaventura.com\\\/en\\\/horarios-de-septiembre\\\/#organizationLogo\",\"width\":500,\"height\":360},\"image\":{\"@id\":\"https:\\\/\\\/entreramasaventura.com\\\/en\\\/horarios-de-septiembre\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/entreramasaventura.com\\\/en\\\/author\\\/entreramas#author\",\"url\":\"https:\\\/\\\/entreramasaventura.com\\\/en\\\/author\\\/entreramas\",\"name\":\"Entre Ramas Aventura\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/entreramasaventura.com\\\/en\\\/horarios-de-septiembre#webpage\",\"url\":\"https:\\\/\\\/entreramasaventura.com\\\/en\\\/horarios-de-septiembre\",\"name\":\"Horarios de Septiembre | Entre Ramas Aventura\",\"inLanguage\":\"en-GB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/entreramasaventura.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/entreramasaventura.com\\\/en\\\/horarios-de-septiembre#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/entreramasaventura.com\\\/en\\\/author\\\/entreramas#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/entreramasaventura.com\\\/en\\\/author\\\/entreramas#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/entreramasaventura.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/A02AD2B8-B612-45E8-96CC-B97127C24C42-scaled.jpeg\",\"@id\":\"https:\\\/\\\/entreramasaventura.com\\\/en\\\/horarios-de-septiembre\\\/#mainImage\",\"width\":2560,\"height\":1341},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/entreramasaventura.com\\\/en\\\/horarios-de-septiembre#mainImage\"},\"datePublished\":\"2020-08-31T10:57:42+02:00\",\"dateModified\":\"2020-08-31T10:57:45+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/entreramasaventura.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/entreramasaventura.com\\\/en\\\/\",\"name\":\"Entre Ramas Aventura\",\"description\":\"Tu parque de aventura en los bosques ubicado en los pinares de Roche\",\"inLanguage\":\"en-GB\",\"publisher\":{\"@id\":\"https:\\\/\\\/entreramasaventura.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Horarios de Septiembre | Entre Ramas Aventura","description":"","canonical_url":"https:\/\/entreramasaventura.com\/en\/horarios-de-septiembre","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/entreramasaventura.com\/en\/horarios-de-septiembre#article","name":"Horarios de Septiembre | Entre Ramas Aventura","headline":"Horarios de Septiembre","author":{"@id":"https:\/\/entreramasaventura.com\/en\/author\/entreramas#author"},"publisher":{"@id":"https:\/\/entreramasaventura.com\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/entreramasaventura.com\/wp-content\/uploads\/2020\/08\/A02AD2B8-B612-45E8-96CC-B97127C24C42-scaled.jpeg","width":2560,"height":1341},"datePublished":"2020-08-31T10:57:42+02:00","dateModified":"2020-08-31T10:57:45+02:00","inLanguage":"en-GB","mainEntityOfPage":{"@id":"https:\/\/entreramasaventura.com\/en\/horarios-de-septiembre#webpage"},"isPartOf":{"@id":"https:\/\/entreramasaventura.com\/en\/horarios-de-septiembre#webpage"},"articleSection":"Sin categorizar, aventura, conil, tirolinas, vacaciones septiembre, Opcional"},{"@type":"BreadcrumbList","@id":"https:\/\/entreramasaventura.com\/en\/horarios-de-septiembre#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/entreramasaventura.com\/en#listItem","position":1,"name":"Inicio","item":"https:\/\/entreramasaventura.com\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/entreramasaventura.com\/category\/sin-categorizar#listItem","name":"Sin categorizar"}},{"@type":"ListItem","@id":"https:\/\/entreramasaventura.com\/category\/sin-categorizar#listItem","position":2,"name":"Sin categorizar","item":"https:\/\/entreramasaventura.com\/category\/sin-categorizar","nextItem":{"@type":"ListItem","@id":"https:\/\/entreramasaventura.com\/en\/horarios-de-septiembre#listItem","name":"Horarios de Septiembre"},"previousItem":{"@type":"ListItem","@id":"https:\/\/entreramasaventura.com\/en#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/entreramasaventura.com\/en\/horarios-de-septiembre#listItem","position":3,"name":"Horarios de Septiembre","previousItem":{"@type":"ListItem","@id":"https:\/\/entreramasaventura.com\/category\/sin-categorizar#listItem","name":"Sin categorizar"}}]},{"@type":"Organization","@id":"https:\/\/entreramasaventura.com\/en\/#organization","name":"Entre Ramas Aventura","description":"Tu parque de aventura en los bosques ubicado en los pinares de Roche","url":"https:\/\/entreramasaventura.com\/en\/","telephone":"+34633698334","logo":{"@type":"ImageObject","url":"https:\/\/entreramasaventura.com\/wp-content\/uploads\/2020\/05\/entre-ramas-logo.png","@id":"https:\/\/entreramasaventura.com\/en\/horarios-de-septiembre\/#organizationLogo","width":500,"height":360},"image":{"@id":"https:\/\/entreramasaventura.com\/en\/horarios-de-septiembre\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/entreramasaventura.com\/en\/author\/entreramas#author","url":"https:\/\/entreramasaventura.com\/en\/author\/entreramas","name":"Entre Ramas Aventura"},{"@type":"WebPage","@id":"https:\/\/entreramasaventura.com\/en\/horarios-de-septiembre#webpage","url":"https:\/\/entreramasaventura.com\/en\/horarios-de-septiembre","name":"Horarios de Septiembre | Entre Ramas Aventura","inLanguage":"en-GB","isPartOf":{"@id":"https:\/\/entreramasaventura.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/entreramasaventura.com\/en\/horarios-de-septiembre#breadcrumblist"},"author":{"@id":"https:\/\/entreramasaventura.com\/en\/author\/entreramas#author"},"creator":{"@id":"https:\/\/entreramasaventura.com\/en\/author\/entreramas#author"},"image":{"@type":"ImageObject","url":"https:\/\/entreramasaventura.com\/wp-content\/uploads\/2020\/08\/A02AD2B8-B612-45E8-96CC-B97127C24C42-scaled.jpeg","@id":"https:\/\/entreramasaventura.com\/en\/horarios-de-septiembre\/#mainImage","width":2560,"height":1341},"primaryImageOfPage":{"@id":"https:\/\/entreramasaventura.com\/en\/horarios-de-septiembre#mainImage"},"datePublished":"2020-08-31T10:57:42+02:00","dateModified":"2020-08-31T10:57:45+02:00"},{"@type":"WebSite","@id":"https:\/\/entreramasaventura.com\/en\/#website","url":"https:\/\/entreramasaventura.com\/en\/","name":"Entre Ramas Aventura","description":"Tu parque de aventura en los bosques ubicado en los pinares de Roche","inLanguage":"en-GB","publisher":{"@id":"https:\/\/entreramasaventura.com\/en\/#organization"}}]},"og:locale":"en_GB","og:site_name":"Entre Ramas Aventura","og:type":"article","og:title":"Horarios de Septiembre | Entre Ramas Aventura","og:url":"https:\/\/entreramasaventura.com\/en\/horarios-de-septiembre","fb:app_id":"2621646948123763","og:image":"https:\/\/entreramasaventura.com\/wp-content\/uploads\/2020\/08\/A02AD2B8-B612-45E8-96CC-B97127C24C42-scaled.jpeg","og:image:secure_url":"https:\/\/entreramasaventura.com\/wp-content\/uploads\/2020\/08\/A02AD2B8-B612-45E8-96CC-B97127C24C42-scaled.jpeg","og:image:width":2560,"og:image:height":1341,"article:published_time":"2020-08-31T08:57:42+00:00","article:modified_time":"2020-08-31T08:57:45+00:00","article:publisher":"https:\/\/es-es.facebook.com\/entre.ramasaventuras","twitter:card":"summary","twitter:title":"Horarios de Septiembre | Entre Ramas Aventura","twitter:image":"https:\/\/entreramasaventura.com\/wp-content\/uploads\/2020\/08\/A02AD2B8-B612-45E8-96CC-B97127C24C42-scaled.jpeg"},"aioseo_meta_data":{"post_id":"2789","title":null,"description":"","keywords":"","keyphrases":null,"primary_term":null,"canonical_url":"","og_title":"","og_description":"","og_object_type":"article","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":"","og_article_tags":"","twitter_use_og":false,"twitter_card":"summary","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-29 15:56:01","updated":"2022-09-16 16:23:30","seo_analyzer_scan_date":null},"_links":{"self":[{"href":"https:\/\/entreramasaventura.com\/en\/wp-json\/wp\/v2\/posts\/2789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/entreramasaventura.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/entreramasaventura.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/entreramasaventura.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/entreramasaventura.com\/en\/wp-json\/wp\/v2\/comments?post=2789"}],"version-history":[{"count":1,"href":"https:\/\/entreramasaventura.com\/en\/wp-json\/wp\/v2\/posts\/2789\/revisions"}],"predecessor-version":[{"id":2792,"href":"https:\/\/entreramasaventura.com\/en\/wp-json\/wp\/v2\/posts\/2789\/revisions\/2792"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/entreramasaventura.com\/en\/wp-json\/wp\/v2\/media\/2790"}],"wp:attachment":[{"href":"https:\/\/entreramasaventura.com\/en\/wp-json\/wp\/v2\/media?parent=2789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/entreramasaventura.com\/en\/wp-json\/wp\/v2\/categories?post=2789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/entreramasaventura.com\/en\/wp-json\/wp\/v2\/tags?post=2789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}